{"id":13990,"date":"2020-08-13T21:40:13","date_gmt":"2020-08-13T21:40:13","guid":{"rendered":"https:\/\/daintl.org\/es-la\/?p=13990"},"modified":"2020-08-13T21:47:00","modified_gmt":"2020-08-13T21:47:00","slug":"el-liderazgo-de-servicio-impacta-comunidades-en-india","status":"publish","type":"post","link":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/","title":{"rendered":"El liderazgo de servicio impacta comunidades en India"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"El liderazgo de servicio impacta comunidades en India\" src=\"https:\/\/player.vimeo.com\/video\/195346813?dnt=1&amp;app_id=122963\" width=\"1080\" height=\"608\" frameborder=\"0\" allow=\"autoplay; fullscreen\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":14010,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[65],"tags":[],"ppma_author":[67],"class_list":["post-13990","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-videos","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El liderazgo de servicio impacta comunidades en India - DAI - Latinoam\u00e9rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El liderazgo de servicio impacta comunidades en India - DAI - Latinoam\u00e9rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/\" \/>\n<meta property=\"og:site_name\" content=\"DAI - Latinoam\u00e9rica\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-13T21:40:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-13T21:47:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/daintl.org\/es\/wp-content\/uploads\/sites\/2\/2020\/08\/608413993_780x439-768x431-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"431\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"DAI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"edgar\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/2020\\\/08\\\/13\\\/el-liderazgo-de-servicio-impacta-comunidades-en-india\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/2020\\\/08\\\/13\\\/el-liderazgo-de-servicio-impacta-comunidades-en-india\\\/\"},\"author\":{\"name\":\"edgar\",\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/#\\\/schema\\\/person\\\/3886e7cf4aa24af49b98edd30a55b1b9\"},\"headline\":\"El liderazgo de servicio impacta comunidades en India\",\"datePublished\":\"2020-08-13T21:40:13+00:00\",\"dateModified\":\"2020-08-13T21:47:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/2020\\\/08\\\/13\\\/el-liderazgo-de-servicio-impacta-comunidades-en-india\\\/\"},\"wordCount\":13,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/2020\\\/08\\\/13\\\/el-liderazgo-de-servicio-impacta-comunidades-en-india\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/daintl.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/608413993_780x439-768x431-1.jpg\",\"articleSection\":[\"Videos\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/daintl.org\\\/es\\\/2020\\\/08\\\/13\\\/el-liderazgo-de-servicio-impacta-comunidades-en-india\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/2020\\\/08\\\/13\\\/el-liderazgo-de-servicio-impacta-comunidades-en-india\\\/\",\"url\":\"https:\\\/\\\/daintl.org\\\/es\\\/2020\\\/08\\\/13\\\/el-liderazgo-de-servicio-impacta-comunidades-en-india\\\/\",\"name\":\"El liderazgo de servicio impacta comunidades en India - DAI - Latinoam\u00e9rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/2020\\\/08\\\/13\\\/el-liderazgo-de-servicio-impacta-comunidades-en-india\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/2020\\\/08\\\/13\\\/el-liderazgo-de-servicio-impacta-comunidades-en-india\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/daintl.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/608413993_780x439-768x431-1.jpg\",\"datePublished\":\"2020-08-13T21:40:13+00:00\",\"dateModified\":\"2020-08-13T21:47:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/#\\\/schema\\\/person\\\/3886e7cf4aa24af49b98edd30a55b1b9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/2020\\\/08\\\/13\\\/el-liderazgo-de-servicio-impacta-comunidades-en-india\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/daintl.org\\\/es\\\/2020\\\/08\\\/13\\\/el-liderazgo-de-servicio-impacta-comunidades-en-india\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/2020\\\/08\\\/13\\\/el-liderazgo-de-servicio-impacta-comunidades-en-india\\\/#primaryimage\",\"url\":\"https:\\\/\\\/daintl.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/608413993_780x439-768x431-1.jpg\",\"contentUrl\":\"https:\\\/\\\/daintl.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/608413993_780x439-768x431-1.jpg\",\"width\":768,\"height\":431},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/2020\\\/08\\\/13\\\/el-liderazgo-de-servicio-impacta-comunidades-en-india\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/daintl.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El liderazgo de servicio impacta comunidades en India\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/daintl.org\\\/es\\\/\",\"name\":\"DAI - Latinoam\u00e9rica\",\"description\":\"Entrenamiento para L\u00edderes Siervos Cristianos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/daintl.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/daintl.org\\\/es\\\/#\\\/schema\\\/person\\\/3886e7cf4aa24af49b98edd30a55b1b9\",\"name\":\"edgar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/622a1433edb072d6520979a034f3ee52e58ea8c4393825c7e57817d868b35dea?s=96&d=mm&r=g5cf59d66a7f69d14c2ff78d9614fc34f\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/622a1433edb072d6520979a034f3ee52e58ea8c4393825c7e57817d868b35dea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/622a1433edb072d6520979a034f3ee52e58ea8c4393825c7e57817d868b35dea?s=96&d=mm&r=g\",\"caption\":\"edgar\"},\"sameAs\":[\"https:\\\/\\\/daintl.org\"],\"url\":\"https:\\\/\\\/daintl.org\\\/es\\\/author\\\/edgar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El liderazgo de servicio impacta comunidades en India - DAI - Latinoam\u00e9rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/","og_locale":"en_US","og_type":"article","og_title":"El liderazgo de servicio impacta comunidades en India - DAI - Latinoam\u00e9rica","og_url":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/","og_site_name":"DAI - Latinoam\u00e9rica","article_published_time":"2020-08-13T21:40:13+00:00","article_modified_time":"2020-08-13T21:47:00+00:00","og_image":[{"width":768,"height":431,"url":"https:\/\/daintl.org\/es\/wp-content\/uploads\/sites\/2\/2020\/08\/608413993_780x439-768x431-1.jpg","type":"image\/jpeg"}],"author":"DAI","twitter_card":"summary_large_image","twitter_misc":{"Written by":"edgar"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/#article","isPartOf":{"@id":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/"},"author":{"name":"edgar","@id":"https:\/\/daintl.org\/es\/#\/schema\/person\/3886e7cf4aa24af49b98edd30a55b1b9"},"headline":"El liderazgo de servicio impacta comunidades en India","datePublished":"2020-08-13T21:40:13+00:00","dateModified":"2020-08-13T21:47:00+00:00","mainEntityOfPage":{"@id":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/"},"wordCount":13,"commentCount":0,"image":{"@id":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/#primaryimage"},"thumbnailUrl":"https:\/\/daintl.org\/es\/wp-content\/uploads\/sites\/2\/2020\/08\/608413993_780x439-768x431-1.jpg","articleSection":["Videos"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/","url":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/","name":"El liderazgo de servicio impacta comunidades en India - DAI - Latinoam\u00e9rica","isPartOf":{"@id":"https:\/\/daintl.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/#primaryimage"},"image":{"@id":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/#primaryimage"},"thumbnailUrl":"https:\/\/daintl.org\/es\/wp-content\/uploads\/sites\/2\/2020\/08\/608413993_780x439-768x431-1.jpg","datePublished":"2020-08-13T21:40:13+00:00","dateModified":"2020-08-13T21:47:00+00:00","author":{"@id":"https:\/\/daintl.org\/es\/#\/schema\/person\/3886e7cf4aa24af49b98edd30a55b1b9"},"breadcrumb":{"@id":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/#primaryimage","url":"https:\/\/daintl.org\/es\/wp-content\/uploads\/sites\/2\/2020\/08\/608413993_780x439-768x431-1.jpg","contentUrl":"https:\/\/daintl.org\/es\/wp-content\/uploads\/sites\/2\/2020\/08\/608413993_780x439-768x431-1.jpg","width":768,"height":431},{"@type":"BreadcrumbList","@id":"https:\/\/daintl.org\/es\/2020\/08\/13\/el-liderazgo-de-servicio-impacta-comunidades-en-india\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/daintl.org\/es\/"},{"@type":"ListItem","position":2,"name":"El liderazgo de servicio impacta comunidades en India"}]},{"@type":"WebSite","@id":"https:\/\/daintl.org\/es\/#website","url":"https:\/\/daintl.org\/es\/","name":"DAI - Latinoam\u00e9rica","description":"Entrenamiento para L\u00edderes Siervos Cristianos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/daintl.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/daintl.org\/es\/#\/schema\/person\/3886e7cf4aa24af49b98edd30a55b1b9","name":"edgar","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/622a1433edb072d6520979a034f3ee52e58ea8c4393825c7e57817d868b35dea?s=96&d=mm&r=g5cf59d66a7f69d14c2ff78d9614fc34f","url":"https:\/\/secure.gravatar.com\/avatar\/622a1433edb072d6520979a034f3ee52e58ea8c4393825c7e57817d868b35dea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/622a1433edb072d6520979a034f3ee52e58ea8c4393825c7e57817d868b35dea?s=96&d=mm&r=g","caption":"edgar"},"sameAs":["https:\/\/daintl.org"],"url":"https:\/\/daintl.org\/es\/author\/edgar\/"}]}},"authors":[{"term_id":67,"user_id":2,"is_guest":0,"slug":"kevin-grenier","display_name":"DAI","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/605a931116b288bf9d0b5f2bfd68c12c8563565d5d31aff7b589bdfac05356e0?s=96&d=mm&r=g","author_category":"","user_url":"https:\/\/daintl.org","last_name":"Grenier","first_name":"Kevin","first_name_2":"","last_name_2":"","user_email_2":"","user_url_2":"","job_title":"","description":"Kevin joined DAI in 2019 after a career that has included work in the non-profit world, small business, pastoral ministry and the military chaplaincy. Kevin is a graduate of the United States Air Force Academy (B.S. in History &amp; International Affairs) and Denver Seminary (M.Div. in Pastoral Counseling). He served as an associate faculty member at Colorado Christian University and Denver Seminary where he taught Greek, homiletics and crisis counseling classes."}],"_links":{"self":[{"href":"https:\/\/daintl.org\/es\/wp-json\/wp\/v2\/posts\/13990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/daintl.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/daintl.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/daintl.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/daintl.org\/es\/wp-json\/wp\/v2\/comments?post=13990"}],"version-history":[{"count":1,"href":"https:\/\/daintl.org\/es\/wp-json\/wp\/v2\/posts\/13990\/revisions"}],"predecessor-version":[{"id":13994,"href":"https:\/\/daintl.org\/es\/wp-json\/wp\/v2\/posts\/13990\/revisions\/13994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/daintl.org\/es\/wp-json\/wp\/v2\/media\/14010"}],"wp:attachment":[{"href":"https:\/\/daintl.org\/es\/wp-json\/wp\/v2\/media?parent=13990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/daintl.org\/es\/wp-json\/wp\/v2\/categories?post=13990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/daintl.org\/es\/wp-json\/wp\/v2\/tags?post=13990"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/daintl.org\/es\/wp-json\/wp\/v2\/ppma_author?post=13990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}